{"id":16492,"date":"2021-08-04T06:27:06","date_gmt":"2021-08-04T06:27:06","guid":{"rendered":"https:\/\/www.syssteel.com\/iso_and_environment\/"},"modified":"2025-09-30T14:12:29","modified_gmt":"2025-09-30T07:12:29","slug":"iso_and_environment","status":"publish","type":"page","link":"https:\/\/www.syssteel.com\/zh-hans\/iso_and_environment\/","title":{"rendered":"Environment"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16492\" class=\"elementor elementor-16492\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-d02e416 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"d02e416\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n                            <div class=\"elementor-background-overlay\"><\/div>\n                \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-505205d\" data-id=\"505205d\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-d9883cb elementor-widget elementor-widget-heading\" data-id=\"d9883cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Environment<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-78e0c805 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78e0c805\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18ee1dbf\" data-id=\"18ee1dbf\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-4c9bec43 elementor-widget elementor-widget-text-editor\" data-id=\"4c9bec43\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>SYS has emphasized on product quality along with environmental stewardship. The company is responsible to society and communities in terms of alternative energy. SYS uses Solar Cell panels to reduce the energy used to generate electricity. SYS has continually recognized the importance of air, monitoring equipment and dust removal systems at the factory shafts.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d62491 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d62491\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a8a291\" data-id=\"1a8a291\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-473e6d7 elementor-widget elementor-widget-image\" data-id=\"473e6d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/1-01-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/1-01-300x300.png 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/1-01-1024x1024.png 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/1-01-150x150.png 150w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/1-01-768x768.png 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/1-01-1536x1536.png 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/1-01-2048x2048.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e3f51cc\" data-id=\"e3f51cc\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-7d20e94 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"7d20e94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h4><span style=\"color: #116ea8;\"><b>H-BEAM steel from SYS is qualified steel material<\/b><\/span><\/h4><p>It is known as Green Building Material according to the principle of 3R (Reduce-Reuse-Recycle) that can be recycled and recycled 99%.<\/p><p>It is the circular economy of raw materials and products to optimize resource efficiency, reduce dependence on natural resources and create sustainable value for the organization and its stakeholders.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad2acb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad2acb1\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-b9cdb7a\" data-id=\"b9cdb7a\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-7a1fe45 elementor-widget elementor-widget-image\" data-id=\"7a1fe45\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-02-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-02-300x300.png 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-02-1024x1024.png 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-02-150x150.png 150w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-02-768x768.png 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-02-1536x1536.png 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-02-2048x2048.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5942465\" data-id=\"5942465\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-522818f elementor-widget elementor-widget-text-editor\" data-id=\"522818f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h4>\u00a0<\/h4><h4><span style=\"color: #116ea8;\">R1 &#8211; Reduce<\/span><\/h4><p>Limit material consumption, increase cost-effectiveness<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-267e286\" data-id=\"267e286\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-ac993ce elementor-widget elementor-widget-image\" data-id=\"ac993ce\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-01-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-01-300x300.png 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-01-1024x1024.png 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-01-150x150.png 150w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-01-768x768.png 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-01-1536x1536.png 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-01-2048x2048.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-d8a2fc8\" data-id=\"d8a2fc8\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-507cb04 elementor-widget elementor-widget-text-editor\" data-id=\"507cb04\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h4>\u00a0<\/h4><h4><span style=\"color: #116ea8;\">R2 &#8211; Reuse<\/span><\/h4><p>Reusable structure<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-e54465c\" data-id=\"e54465c\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-8d8fe72 elementor-widget elementor-widget-image\" data-id=\"8d8fe72\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-03-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-03-300x300.png 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-03-1024x1024.png 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-03-150x150.png 150w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-03-768x768.png 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-03-1536x1536.png 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/2-03-2048x2048.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-a0a6929\" data-id=\"a0a6929\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-9ac9a4b elementor-widget elementor-widget-text-editor\" data-id=\"9ac9a4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h4>\u00a0<\/h4><h4><span style=\"color: #116ea8;\">R3 &#8211; Recycle<\/span><\/h4><p>100% recycle<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c0a754 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c0a754\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9827a98\" data-id=\"9827a98\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-158df69 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"158df69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h5><span style=\"color: #116ea8;\"><b>EAF steel production process from <\/b><b>100% <\/b><b>recycled raw materials.<\/b><\/span><\/h5><p>EAF or Electric Arc Furnace is SYS steel manufacturing process by Arc welding method, selecting 100% recycled steel raw materials for remelting with electric power through chemical composition control to meet advance standards.<\/p><p>Electric Arc Furnace (EAF) will be able to control the quality of steel more precisely. Structural steel is of high quality and energy saving compared to other steel fabrication technologies.<\/p><p>In addition to the production process of SYS with EAF (Electric Arc Furnace) design, high-quality structural steel is obtained, it is also an environmentally friendly production process.<\/p><p>It is a manufacturing process that uses iron to melt using electricity. It emits less carbon dioxide (CO2) than the Blast Furnace process, which uses iron ore to smelt and use coal for energy. SYS&#8217;s production plays a part in reducing greenhouse gas emissions and conserving the environment as much as possible.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41a4902\" data-id=\"41a4902\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-bfeae82 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"bfeae82\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"115\" height=\"300\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/3-01-e1643621454703-115x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/3-01-e1643621454703-115x300.png 115w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/3-01-e1643621454703.png 299w\" sizes=\"(max-width: 115px) 100vw, 115px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">EAF<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2bc2f3e\" data-id=\"2bc2f3e\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap\">\n                                    <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-f61ff46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f61ff46\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b91fb69\" data-id=\"b91fb69\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-7739d27 elementor-widget elementor-widget-text-editor\" data-id=\"7739d27\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong><span style=\"color: #116ea8;\">SYS has been certified for environmental standards from the following agencies:<br \/>Environmental certifications of SYS<\/span><\/strong><\/h3><p><strong><span style=\"color: #116ea8;\"><img class=\"wp-image-13914 size-medium aligncenter\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/sys-iso-700x109-1-300x59.jpg\" alt=\"\" width=\"300\" height=\"59\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/sys-iso-700x109-1-300x59.jpg 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/sys-iso-700x109-1-1024x200.jpg 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/sys-iso-700x109-1-768x150.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/sys-iso-700x109-1-1536x300.jpg 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/sys-iso-700x109-1-2048x401.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/span><\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb9b3a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb9b3a9\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7707975\" data-id=\"7707975\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-d017ac9 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"d017ac9\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/10\/42.-Siam-Yamato-Steel_Climate-Action-Certificates_2024-2025-300x212.jpg\" alt=\"Climate Action Data Provider\" \/><figcaption class=\"elementor-image-carousel-caption\">Climate Action Data Provider<\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/11\/CFP-by-TGO-01-01-212x300.jpg\" alt=\"CFP by TGO\" \/><figcaption class=\"elementor-image-carousel-caption\">CFP by TGO<\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/CFO-TGO-Certification_2023_SYS-227x300.png\" alt=\"CFO by TGO\" \/><figcaption class=\"elementor-image-carousel-caption\">CFO by TGO<\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-226x300.jpg\" alt=\"CFR by TGO\" \/><figcaption class=\"elementor-image-carousel-caption\">CFR by TGO<\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/10\/CE-CFP-Circular-Economy-CFP-01-208x300.jpg\" alt=\"CE-CFP (Circular Economy- CFP)\" \/><figcaption class=\"elementor-image-carousel-caption\">CE-CFP (Circular Economy- CFP)<\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/09\/TIS-14001-2559-ISO-14001-2015_page-0001-212x300.jpg\" alt=\"ISO 14001 : 2015\tEnvironmental Management System\" \/><figcaption class=\"elementor-image-carousel-caption\">ISO 14001 : 2015\tEnvironmental Management System<\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14064-1-SIAM-YAMATO-STEEL-2023-212x300.jpg\" alt=\"ISO 14064-1 : 2018\tGreenhouse Gases Verification Statement\" \/><figcaption class=\"elementor-image-carousel-caption\">ISO 14064-1 : 2018\tGreenhouse Gases Verification Statement <\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-212x300.jpg\" alt=\"ISO 14067 : 2018\tProduct Carbon Footprint Statement\" \/><figcaption class=\"elementor-image-carousel-caption\">ISO 14067 : 2018\tProduct Carbon Footprint Statement<\/figcaption><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018-1-212x300.jpg\" alt=\"ISO 50001 : 2018\tEnergy Management System\" \/><figcaption class=\"elementor-image-carousel-caption\">ISO 50001 : 2018\tEnergy Management System<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i class=\"eicon-chevron-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i class=\"eicon-chevron-right\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed320eb elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed320eb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            \n                        <div class=\"elementor-container elementor-column-gap-wide \">\n                    <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c4a4c0e\" data-id=\"c4a4c0e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-b587b89 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"b587b89\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"1397\" height=\"987\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/worldsteel-climate-action-certificate-siam-yamato-steel-company-limited.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/worldsteel-climate-action-certificate-siam-yamato-steel-company-limited.jpg 1397w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/worldsteel-climate-action-certificate-siam-yamato-steel-company-limited-300x212.jpg 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/worldsteel-climate-action-certificate-siam-yamato-steel-company-limited-1024x723.jpg 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/worldsteel-climate-action-certificate-siam-yamato-steel-company-limited-768x543.jpg 768w\" sizes=\"(max-width: 1397px) 100vw, 1397px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><br>Climate Action Data Provider<\/h3><p class=\"elementor-image-box-description\">SYS1, SYS2<br><br><\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4764566 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4764566\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/worldsteel-climate-action-certificate-siam-yamato-steel-company-limited.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3c87a48\" data-id=\"3c87a48\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-467d498 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"467d498\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"807\" height=\"1041\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/EPD.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/EPD.jpg 807w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/EPD-233x300.jpg 233w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/EPD-794x1024.jpg 794w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/EPD-768x991.jpg 768w\" sizes=\"(max-width: 807px) 100vw, 807px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">EPD - Environmental Product Declaration<br><\/h3><p class=\"elementor-image-box-description\">SYS1, SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4094b47 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4094b47\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/EPD_SYS2025.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-28ba825\" data-id=\"28ba825\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-91e0c7f elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"91e0c7f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"1927\" height=\"2560\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFP_2023-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFP_2023-1-scaled.jpg 1927w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFP_2023-1-226x300.jpg 226w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFP_2023-1-771x1024.jpg 771w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFP_2023-1-768x1020.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFP_2023-1-1156x1536.jpg 1156w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFP_2023-1-1541x2048.jpg 1541w\" sizes=\"(max-width: 1927px) 100vw, 1927px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CFP by TGO <\/h3><p class=\"elementor-image-box-description\">SYS1,SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e58714 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1e58714\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/11\/CFP-by-TGO-2023.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-31dc4b7\" data-id=\"31dc4b7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-caed49c elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"caed49c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"1927\" height=\"2560\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-scaled.jpg 1927w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-226x300.jpg 226w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-771x1024.jpg 771w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-768x1020.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-1156x1536.jpg 1156w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023-1-1541x2048.jpg 1541w\" sizes=\"(max-width: 1927px) 100vw, 1927px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CFR by TGO<\/h3><p class=\"elementor-image-box-description\">SYS1, SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c1fcf0 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"7c1fcf0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CFR_2023.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d9ab58d\" data-id=\"d9ab58d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-9de3547 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"9de3547\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"1769\" height=\"2560\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023-1-scaled.jpg 1769w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023-1-207x300.jpg 207w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023-1-707x1024.jpg 707w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023-1-768x1112.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023-1-1061x1536.jpg 1061w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023-1-1415x2048.jpg 1415w\" sizes=\"(max-width: 1769px) 100vw, 1769px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CE-CFP (Circular Economy- CFP)<\/h3><p class=\"elementor-image-box-description\">SYS1, SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3803b4 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"e3803b4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/TGO-CE-CFP_2023.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4a4f63 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4a4f63\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            \n                        <div class=\"elementor-container elementor-column-gap-wide \">\n                    <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0eca09e\" data-id=\"0eca09e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-1efcc14 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"1efcc14\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"741\" height=\"1041\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/ISO14064-1_SYS2025.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/ISO14064-1_SYS2025.jpg 741w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/ISO14064-1_SYS2025-214x300.jpg 214w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/ISO14064-1_SYS2025-729x1024.jpg 729w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ISO 14064-1 : 2018 Bureau Veritas Certification<\/h3><p class=\"elementor-image-box-description\">SYS1, SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd408b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4fd408b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/ISO14064-1_SYS2025.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9a34579\" data-id=\"9a34579\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-ca9cbe3 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"ca9cbe3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"1810\" height=\"2560\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-scaled.jpg 1810w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-212x300.jpg 212w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-724x1024.jpg 724w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-768x1087.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-1086x1536.jpg 1086w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023-1-1448x2048.jpg 1448w\" sizes=\"(max-width: 1810px) 100vw, 1810px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ISO 14067-1 : 2018 Bureau Veritas Certification<\/h3><p class=\"elementor-image-box-description\">SYS1, SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07d518a elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"07d518a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2024\/07\/ISO14067_2023.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-af65bcc\" data-id=\"af65bcc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-80e8e45 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"80e8e45\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"737\" height=\"1045\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/05\/SYS_Certificate-of-ISO-14001_2015-Expire-2027.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/05\/SYS_Certificate-of-ISO-14001_2015-Expire-2027.jpg 737w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/05\/SYS_Certificate-of-ISO-14001_2015-Expire-2027-212x300.jpg 212w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/05\/SYS_Certificate-of-ISO-14001_2015-Expire-2027-722x1024.jpg 722w\" sizes=\"(max-width: 737px) 100vw, 737px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ISO 14001--2015 Environmental Management System <\/h3><p class=\"elementor-image-box-description\">SYS1,SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c16867d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c16867d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/05\/SYS_Certificate-of-ISO-14001_2015-Expire-2027.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5fd98c3\" data-id=\"5fd98c3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-36edb95 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"36edb95\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"1448\" height=\"2048\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018-1-scaled.jpg 1448w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018-1-212x300.jpg 212w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018-1-724x1024.jpg 724w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018-1-768x1086.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018-1-1086x1536.jpg 1086w\" sizes=\"(max-width: 1448px) 100vw, 1448px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ISO 50001-2018 Energy Management System <\/h3><p class=\"elementor-image-box-description\">SYS1,SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-284a7a8 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"284a7a8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/07\/ISO-50001_2018.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c68647b\" data-id=\"c68647b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-2162ab9 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"2162ab9\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"702\" height=\"1003\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/SGBP_SYS2025.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/SGBP_SYS2025.jpg 702w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/SGBP_SYS2025-210x300.jpg 210w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">SGBP - SINGAPORE GREEN BUILDING PRODUCT CERTIFICATE<\/h3><p class=\"elementor-image-box-description\">SYS1,SYS2<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-756dd52 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"756dd52\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/07\/SGBP_SYS2025.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-e50e72c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e50e72c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            \n                        <div class=\"elementor-container elementor-column-gap-wide \">\n                    <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e7824a4\" data-id=\"e7824a4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-2f23665 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"2f23665\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-MTP.pdf\" target=\"_blank\"><img width=\"737\" height=\"1045\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-MTP.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-MTP.jpg 737w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-MTP-212x300.jpg 212w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-MTP-722x1024.jpg 722w\" sizes=\"(max-width: 737px) 100vw, 737px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-MTP.pdf\" target=\"_blank\">Green Industry Level 4 (Green Culture)<\/a><\/h3><p class=\"elementor-image-box-description\">SYS1<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98afb0a elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"98afb0a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-MTP.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f055da8\" data-id=\"f055da8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-9c6a11e elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"9c6a11e\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-HP.pdf\" target=\"_blank\"><img width=\"737\" height=\"1043\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-HP.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-HP.jpg 737w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-HP-212x300.jpg 212w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-HP-724x1024.jpg 724w\" sizes=\"(max-width: 737px) 100vw, 737px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-HP.pdf\" target=\"_blank\">Green Industry Level 4 (Green Culture)<\/a><\/h3><p class=\"elementor-image-box-description\">SYS1<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ac130e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1ac130e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2025\/09\/Green-Industy-SYS-HP.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4209d38\" data-id=\"4209d38\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap\">\n                                    <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d55bcd1\" data-id=\"d55bcd1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap\">\n                                    <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e8fcdcf\" data-id=\"e8fcdcf\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            <div class=\"elementor-widget-wrap\">\n                                    <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6e8f22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6e8f22\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9cc9bec\" data-id=\"9cc9bec\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-25eb40b elementor-aspect-ratio-169 elementor-invisible elementor-widget elementor-widget-video\" data-id=\"25eb40b\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/Xu6VsmH8YZo&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;,&quot;aspect_ratio&quot;:&quot;169&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-fit-aspect-ratio elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-92abead elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92abead\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e21a31\" data-id=\"8e21a31\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-b8252b4 elementor-widget elementor-widget-text-editor\" data-id=\"b8252b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><span style=\"color: #ffffff;\"><b>Recommend for you<\/b><\/span><\/h4>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f70785 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f70785\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48065c9\" data-id=\"48065c9\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-0e672dc elementor-widget elementor-widget-image\" data-id=\"0e672dc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.syssteel.com\/en\/blog-en\/solar-rooftop-a-clean-energy-solution-for-the-modern-industrial-sector\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img width=\"640\" height=\"427\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Solar-Rooftop-A-Clean-Energy-Solution-for-the-Modern-Industrial-Sector-01-cover-01-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Solar-Rooftop-A-Clean-Energy-Solution-for-the-Modern-Industrial-Sector-01-cover-01-1024x683.jpg 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Solar-Rooftop-A-Clean-Energy-Solution-for-the-Modern-Industrial-Sector-01-cover-01-300x200.jpg 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Solar-Rooftop-A-Clean-Energy-Solution-for-the-Modern-Industrial-Sector-01-cover-01-768x512.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Solar-Rooftop-A-Clean-Energy-Solution-for-the-Modern-Industrial-Sector-01-cover-01-1536x1024.jpg 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Solar-Rooftop-A-Clean-Energy-Solution-for-the-Modern-Industrial-Sector-01-cover-01-2048x1366.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79d2cb7\" data-id=\"79d2cb7\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-f514337 elementor-widget elementor-widget-image\" data-id=\"f514337\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.syssteel.com\/en\/blog-en\/change-for-the-world-and-efficiency-of-construction-business-through-circular-economy\/\">\n\t\t\t\t\t\t\t<img width=\"640\" height=\"427\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Change-for-the-World-and-Efficiency-of-Construction-Business-through-Circular-Economy-01-2-1024x683.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Change-for-the-World-and-Efficiency-of-Construction-Business-through-Circular-Economy-01-2-1024x683.png 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Change-for-the-World-and-Efficiency-of-Construction-Business-through-Circular-Economy-01-2-300x200.png 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Change-for-the-World-and-Efficiency-of-Construction-Business-through-Circular-Economy-01-2-768x512.png 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Change-for-the-World-and-Efficiency-of-Construction-Business-through-Circular-Economy-01-2-1536x1024.png 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/Change-for-the-World-and-Efficiency-of-Construction-Business-through-Circular-Economy-01-2-2048x1366.png 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-773e50a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"773e50a\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c436a0c\" data-id=\"c436a0c\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-c545676 elementor-widget elementor-widget-image\" data-id=\"c545676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.syssteel.com\/en\/blog-en\/carbon-credit-a-policy-to-ensure-safety-for-all-users-and-the-environment-since-the-production-process\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img width=\"640\" height=\"427\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/02-CARBON-CREDIT_ENG-Recovered-01-2-1024x683.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/02-CARBON-CREDIT_ENG-Recovered-01-2-1024x683.png 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/02-CARBON-CREDIT_ENG-Recovered-01-2-300x200.png 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/02-CARBON-CREDIT_ENG-Recovered-01-2-768x512.png 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/02-CARBON-CREDIT_ENG-Recovered-01-2-1536x1024.png 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/02-CARBON-CREDIT_ENG-Recovered-01-2-2048x1366.png 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73f9796\" data-id=\"73f9796\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-2eebde3 elementor-widget elementor-widget-image\" data-id=\"2eebde3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.syssteel.com\/en\/blog-en\/be-friendly-to-your-surroundings-and-cut-resource-usage-with-the-h-beam-steel-structure\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img width=\"640\" height=\"427\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/BEFRIE1-01-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/BEFRIE1-01-1024x683.jpg 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/BEFRIE1-01-300x200.jpg 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/BEFRIE1-01-768x512.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/BEFRIE1-01-1536x1024.jpg 1536w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/06\/BEFRIE1-01-2048x1366.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4f75f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4f75f7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n            \n                        <div class=\"elementor-container elementor-column-gap-default \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-163c7a4\" data-id=\"163c7a4\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-58393f3 elementor-widget elementor-widget-text-editor\" data-id=\"58393f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p><img class=\"alignnone size-full wp-image-7872\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2020\/02\/cart-icon.png\" alt=\"\" width=\"20\" height=\"20\" \/> Interested to order<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-89dcf38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89dcf38\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-default \">\n                    <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c00f8a2\" data-id=\"c00f8a2\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-3a2ecee elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3a2ecee\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/en\/stockist-malaysia\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Dealers SYS<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-53cdeb5\" data-id=\"53cdeb5\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-d2b0797 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"d2b0797\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"\/download\/?tax%5Bwpdmcategory%5D=%E0%B9%81%E0%B8%84%E0%B9%87%E0%B8%95%E0%B8%95%E0%B8%B2%E0%B8%A5%E0%B9%87%E0%B8%AD%E0%B8%81%E0%B8%A1%E0%B8%B2%E0%B8%95%E0%B8%A3%E0%B8%90%E0%B8%B2%E0%B8%99%E0%B9%84%E0%B8%97%E0%B8%A2\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Catalog Thai Standard<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1c20ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1c20ce\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-default \">\n                    <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8389974\" data-id=\"8389974\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-6d70143 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"6d70143\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/06\/SYS-Catalog-Inter_Effective-June-2023.pdf\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Catalog International Standard<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-418db55\" data-id=\"418db55\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-d46135f elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"d46135f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"mailto:sys@syssteel.com\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Email : sys@syssteel.com<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                    <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-abc2700 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abc2700\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-no \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c59e4c1\" data-id=\"c59e4c1\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-eb02790 elementor-widget elementor-widget-image\" data-id=\"eb02790\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"640\" height=\"80\" src=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/01\/Contact-01-768x96.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/01\/Contact-01-768x96.jpg 768w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/01\/Contact-01-300x38.jpg 300w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/01\/Contact-01-1024x128.jpg 1024w, https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/01\/Contact-01.jpg 1280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-89b2176 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89b2176\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-default \">\n                                <\/div>\n        <\/section>\n        \t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Environment SYS has emphasized on product quality along with environmental stewardship. The company is responsible to society and communities in terms of alternative energy. SYS uses Solar Cell panels to reduce the energy used to generate electricity. SYS has continually recognized the importance of air, monitoring equipment and dust removal systems at the factory shafts. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16493,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":[],"categories":[],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Environment - SIAM YAMATO STEEL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Environment - SIAM YAMATO STEEL\" \/>\n<meta property=\"og:description\" content=\"Environment SYS has emphasized on product quality along with environmental stewardship. The company is responsible to society and communities in terms of alternative energy. SYS uses Solar Cell panels to reduce the energy used to generate electricity. SYS has continually recognized the importance of air, monitoring equipment and dust removal systems at the factory shafts. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/\" \/>\n<meta property=\"og:site_name\" content=\"SIAM YAMATO STEEL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/syssteel\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T07:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.syssteel.com\/siam-yamato-steel\/wp-content\/uploads\/2022\/01\/environment.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/#organization\",\"name\":\"Siam Yamato Steel (SYS)\",\"url\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/syssteel\/\",\"https:\/\/www.instagram.com\/syssteel\/\",\"https:\/\/www.youtube.com\/@SYSSteelchannel\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/#logo\",\"inLanguage\":\"cn\",\"url\":\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/syssteel-logo.png\",\"contentUrl\":\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/syssteel-logo.png\",\"width\":118,\"height\":49,\"caption\":\"Siam Yamato Steel (SYS)\"},\"image\":{\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/#website\",\"url\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/\",\"name\":\"SIAM YAMATO STEEL\",\"description\":\"SYS \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e14\u0e35\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e27\u0e49\u0e43\u0e08 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e17\u0e22\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e01\u0e23\u0e35\u0e19 \u0e04\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 30 \u0e1b\u0e35 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e21\u0e35\u0e43\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e38\u0e01\u0e17\u0e48\u0e2d\u0e19 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08 \u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\",\"publisher\":{\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cn\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#primaryimage\",\"inLanguage\":\"cn\",\"url\":\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/environment.jpg\",\"contentUrl\":\"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/environment.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#webpage\",\"url\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/\",\"name\":\"Environment - SIAM YAMATO STEEL\",\"isPartOf\":{\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#primaryimage\"},\"datePublished\":\"2021-08-04T06:27:06+00:00\",\"dateModified\":\"2025-09-30T07:12:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#breadcrumb\"},\"inLanguage\":\"cn\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.syssteel.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Environment\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Environment - SIAM YAMATO STEEL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/","og_locale":"en_US","og_type":"article","og_title":"Environment - SIAM YAMATO STEEL","og_description":"Environment SYS has emphasized on product quality along with environmental stewardship. The company is responsible to society and communities in terms of alternative energy. SYS uses Solar Cell panels to reduce the energy used to generate electricity. SYS has continually recognized the importance of air, monitoring equipment and dust removal systems at the factory shafts. [&hellip;]","og_url":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/","og_site_name":"SIAM YAMATO STEEL","article_publisher":"https:\/\/www.facebook.com\/syssteel\/","article_modified_time":"2025-09-30T07:12:29+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.syssteel.com\/siam-yamato-steel\/wp-content\/uploads\/2022\/01\/environment.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/#organization","name":"Siam Yamato Steel (SYS)","url":"https:\/\/www.syssteel.com\/siam-yamato-steel\/","sameAs":["https:\/\/www.facebook.com\/syssteel\/","https:\/\/www.instagram.com\/syssteel\/","https:\/\/www.youtube.com\/@SYSSteelchannel"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/#logo","inLanguage":"cn","url":"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/syssteel-logo.png","contentUrl":"https:\/\/www.syssteel.com\/wp-content\/uploads\/2023\/08\/syssteel-logo.png","width":118,"height":49,"caption":"Siam Yamato Steel (SYS)"},"image":{"@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/#website","url":"https:\/\/www.syssteel.com\/siam-yamato-steel\/","name":"SIAM YAMATO STEEL","description":"SYS \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e14\u0e35\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e27\u0e49\u0e43\u0e08 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e17\u0e22\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e01\u0e23\u0e35\u0e19 \u0e04\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 30 \u0e1b\u0e35 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e21\u0e35\u0e43\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e38\u0e01\u0e17\u0e48\u0e2d\u0e19 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08 \u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","publisher":{"@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.syssteel.com\/siam-yamato-steel\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cn"},{"@type":"ImageObject","@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#primaryimage","inLanguage":"cn","url":"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/environment.jpg","contentUrl":"https:\/\/www.syssteel.com\/wp-content\/uploads\/2022\/01\/environment.jpg","width":1024,"height":576},{"@type":"WebPage","@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#webpage","url":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/","name":"Environment - SIAM YAMATO STEEL","isPartOf":{"@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#primaryimage"},"datePublished":"2021-08-04T06:27:06+00:00","dateModified":"2025-09-30T07:12:29+00:00","breadcrumb":{"@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#breadcrumb"},"inLanguage":"cn","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.syssteel.com\/siam-yamato-steel\/zh-hans\/iso_and_environment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.syssteel.com\/"},{"@type":"ListItem","position":2,"name":"Environment"}]}]}},"_links":{"self":[{"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/pages\/16492"}],"collection":[{"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=16492"}],"version-history":[{"count":54,"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/pages\/16492\/revisions"}],"predecessor-version":[{"id":22082,"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/pages\/16492\/revisions\/22082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/media\/16493"}],"wp:attachment":[{"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=16492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/categories?post=16492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.syssteel.com\/zh-hans\/wp-json\/wp\/v2\/tags?post=16492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}